{"id":3052,"date":"2022-09-06T19:59:52","date_gmt":"2022-09-07T00:59:52","guid":{"rendered":"https:\/\/recrea.jalisco.gob.mx\/direccion-educacion-indigena\/?page_id=3052"},"modified":"2022-09-06T20:00:51","modified_gmt":"2022-09-07T01:00:51","slug":"organigrama","status":"publish","type":"page","link":"https:\/\/apprende.jalisco.gob.mx\/direccion-educacion-indigena\/organigrama\/","title":{"rendered":"Organigrama"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"3052\" class=\"elementor elementor-3052\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ddfb6fd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ddfb6fd\" data-element_type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b5fef51\" data-id=\"b5fef51\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7c6b08c elementor-widget elementor-widget-breadcrumbs\" data-id=\"7c6b08c\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div id=\"breadcrumbs\"><span><span><a href=\"https:\/\/apprende.jalisco.gob.mx\/direccion-educacion-indigena\/\">Inicio<\/a><\/span><\/span><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2496b07 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"2496b07\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-abc373b\" data-id=\"abc373b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-82a360c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"82a360c\" data-element_type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-177f601\" data-id=\"177f601\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6db45a8 elementor-widget elementor-widget-heading\" data-id=\"6db45a8\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Organigrama<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5487cb7 elementor-widget elementor-widget-text-editor\" data-id=\"5487cb7\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8403013 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8403013\" data-element_type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-abe781a\" data-id=\"abe781a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8d6e71e elementor-widget elementor-widget-text-editor\" data-id=\"8d6e71e\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f166a1 elementor-widget elementor-widget-image\" data-id=\"4f166a1\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"696\" src=\"https:\/\/apprende.jalisco.gob.mx\/direccion-educacion-indigena\/wp-content\/uploads\/sites\/8\/2022\/09\/Mesa-de-trabajo-1@3x-1024x696.png\" class=\"attachment-large size-large wp-image-3054\" alt=\"\" srcset=\"https:\/\/apprende.jalisco.gob.mx\/direccion-educacion-indigena\/wp-content\/uploads\/sites\/8\/2022\/09\/Mesa-de-trabajo-1@3x-1024x696.png 1024w, https:\/\/apprende.jalisco.gob.mx\/direccion-educacion-indigena\/wp-content\/uploads\/sites\/8\/2022\/09\/Mesa-de-trabajo-1@3x-300x204.png 300w, https:\/\/apprende.jalisco.gob.mx\/direccion-educacion-indigena\/wp-content\/uploads\/sites\/8\/2022\/09\/Mesa-de-trabajo-1@3x-768x522.png 768w, https:\/\/apprende.jalisco.gob.mx\/direccion-educacion-indigena\/wp-content\/uploads\/sites\/8\/2022\/09\/Mesa-de-trabajo-1@3x-1536x1043.png 1536w, https:\/\/apprende.jalisco.gob.mx\/direccion-educacion-indigena\/wp-content\/uploads\/sites\/8\/2022\/09\/Mesa-de-trabajo-1@3x-2048x1391.png 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"","ep_exclude_from_search":false,"footnotes":""},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v17.7 (Yoast SEO v21.0) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Organigrama - Direcci\u00f3n de Educaci\u00f3n Ind\u00edgena<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/apprende.jalisco.gob.mx\/direccion-educacion-indigena\/organigrama\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Organigrama\" \/>\n<meta property=\"og:url\" content=\"https:\/\/apprende.jalisco.gob.mx\/direccion-educacion-indigena\/organigrama\/\" \/>\n<meta property=\"og:site_name\" content=\"Direcci\u00f3n de Educaci\u00f3n Ind\u00edgena\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-07T01:00:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/recrea.jalisco.gob.mx\/direccion-educacion-indigena\/wp-content\/uploads\/sites\/8\/2022\/09\/Mesa-de-trabajo-1@3x-1024x696.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/apprende.jalisco.gob.mx\/direccion-educacion-indigena\/organigrama\/\",\"url\":\"https:\/\/apprende.jalisco.gob.mx\/direccion-educacion-indigena\/organigrama\/\",\"name\":\"Organigrama - Direcci\u00f3n de Educaci\u00f3n Ind\u00edgena\",\"isPartOf\":{\"@id\":\"https:\/\/apprende.jalisco.gob.mx\/direccion-educacion-indigena\/#website\"},\"datePublished\":\"2022-09-07T00:59:52+00:00\",\"dateModified\":\"2022-09-07T01:00:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/apprende.jalisco.gob.mx\/direccion-educacion-indigena\/organigrama\/#breadcrumb\"},\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/apprende.jalisco.gob.mx\/direccion-educacion-indigena\/organigrama\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/apprende.jalisco.gob.mx\/direccion-educacion-indigena\/organigrama\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/apprende.jalisco.gob.mx\/direccion-educacion-indigena\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Organigrama\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/apprende.jalisco.gob.mx\/direccion-educacion-indigena\/#website\",\"url\":\"https:\/\/apprende.jalisco.gob.mx\/direccion-educacion-indigena\/\",\"name\":\"Direcci\u00f3n de Educaci\u00f3n Ind\u00edgena\",\"description\":\"Micrositio\",\"publisher\":{\"@id\":\"https:\/\/apprende.jalisco.gob.mx\/direccion-educacion-indigena\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/apprende.jalisco.gob.mx\/direccion-educacion-indigena\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-MX\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/apprende.jalisco.gob.mx\/direccion-educacion-indigena\/#organization\",\"name\":\"Direcci\u00f3n de Educaci\u00f3n Ind\u00edgena\",\"url\":\"https:\/\/apprende.jalisco.gob.mx\/direccion-educacion-indigena\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\/\/apprende.jalisco.gob.mx\/direccion-educacion-indigena\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/apprende.jalisco.gob.mx\/direccion-educacion-indigena\/wp-content\/uploads\/sites\/8\/2022\/03\/logo-Educacion2025.png\",\"contentUrl\":\"https:\/\/apprende.jalisco.gob.mx\/direccion-educacion-indigena\/wp-content\/uploads\/sites\/8\/2022\/03\/logo-Educacion2025.png\",\"width\":427,\"height\":108,\"caption\":\"Direcci\u00f3n de Educaci\u00f3n Ind\u00edgena\"},\"image\":{\"@id\":\"https:\/\/apprende.jalisco.gob.mx\/direccion-educacion-indigena\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Organigrama - Direcci\u00f3n de Educaci\u00f3n Ind\u00edgena","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/apprende.jalisco.gob.mx\/direccion-educacion-indigena\/organigrama\/","og_locale":"es_MX","og_type":"article","og_title":"Organigrama","og_url":"https:\/\/apprende.jalisco.gob.mx\/direccion-educacion-indigena\/organigrama\/","og_site_name":"Direcci\u00f3n de Educaci\u00f3n Ind\u00edgena","article_modified_time":"2022-09-07T01:00:51+00:00","og_image":[{"url":"https:\/\/recrea.jalisco.gob.mx\/direccion-educacion-indigena\/wp-content\/uploads\/sites\/8\/2022\/09\/Mesa-de-trabajo-1@3x-1024x696.png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/apprende.jalisco.gob.mx\/direccion-educacion-indigena\/organigrama\/","url":"https:\/\/apprende.jalisco.gob.mx\/direccion-educacion-indigena\/organigrama\/","name":"Organigrama - Direcci\u00f3n de Educaci\u00f3n Ind\u00edgena","isPartOf":{"@id":"https:\/\/apprende.jalisco.gob.mx\/direccion-educacion-indigena\/#website"},"datePublished":"2022-09-07T00:59:52+00:00","dateModified":"2022-09-07T01:00:51+00:00","breadcrumb":{"@id":"https:\/\/apprende.jalisco.gob.mx\/direccion-educacion-indigena\/organigrama\/#breadcrumb"},"inLanguage":"es-MX","potentialAction":[{"@type":"ReadAction","target":["https:\/\/apprende.jalisco.gob.mx\/direccion-educacion-indigena\/organigrama\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/apprende.jalisco.gob.mx\/direccion-educacion-indigena\/organigrama\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/apprende.jalisco.gob.mx\/direccion-educacion-indigena\/"},{"@type":"ListItem","position":2,"name":"Organigrama"}]},{"@type":"WebSite","@id":"https:\/\/apprende.jalisco.gob.mx\/direccion-educacion-indigena\/#website","url":"https:\/\/apprende.jalisco.gob.mx\/direccion-educacion-indigena\/","name":"Direcci\u00f3n de Educaci\u00f3n Ind\u00edgena","description":"Micrositio","publisher":{"@id":"https:\/\/apprende.jalisco.gob.mx\/direccion-educacion-indigena\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/apprende.jalisco.gob.mx\/direccion-educacion-indigena\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-MX"},{"@type":"Organization","@id":"https:\/\/apprende.jalisco.gob.mx\/direccion-educacion-indigena\/#organization","name":"Direcci\u00f3n de Educaci\u00f3n Ind\u00edgena","url":"https:\/\/apprende.jalisco.gob.mx\/direccion-educacion-indigena\/","logo":{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/apprende.jalisco.gob.mx\/direccion-educacion-indigena\/#\/schema\/logo\/image\/","url":"https:\/\/apprende.jalisco.gob.mx\/direccion-educacion-indigena\/wp-content\/uploads\/sites\/8\/2022\/03\/logo-Educacion2025.png","contentUrl":"https:\/\/apprende.jalisco.gob.mx\/direccion-educacion-indigena\/wp-content\/uploads\/sites\/8\/2022\/03\/logo-Educacion2025.png","width":427,"height":108,"caption":"Direcci\u00f3n de Educaci\u00f3n Ind\u00edgena"},"image":{"@id":"https:\/\/apprende.jalisco.gob.mx\/direccion-educacion-indigena\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/apprende.jalisco.gob.mx\/direccion-educacion-indigena\/wp-json\/wp\/v2\/pages\/3052"}],"collection":[{"href":"https:\/\/apprende.jalisco.gob.mx\/direccion-educacion-indigena\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/apprende.jalisco.gob.mx\/direccion-educacion-indigena\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/apprende.jalisco.gob.mx\/direccion-educacion-indigena\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/apprende.jalisco.gob.mx\/direccion-educacion-indigena\/wp-json\/wp\/v2\/comments?post=3052"}],"version-history":[{"count":4,"href":"https:\/\/apprende.jalisco.gob.mx\/direccion-educacion-indigena\/wp-json\/wp\/v2\/pages\/3052\/revisions"}],"predecessor-version":[{"id":3057,"href":"https:\/\/apprende.jalisco.gob.mx\/direccion-educacion-indigena\/wp-json\/wp\/v2\/pages\/3052\/revisions\/3057"}],"wp:attachment":[{"href":"https:\/\/apprende.jalisco.gob.mx\/direccion-educacion-indigena\/wp-json\/wp\/v2\/media?parent=3052"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}