{"id":11,"date":"2022-03-17T18:40:56","date_gmt":"2022-03-17T18:40:56","guid":{"rendered":"https:\/\/recrea.jalisco.gob.mx\/programa-sigamos-aprendiendo-hospital\/?page_id=11"},"modified":"2026-01-28T10:56:55","modified_gmt":"2026-01-28T16:56:55","slug":"inicio","status":"publish","type":"page","link":"https:\/\/apprende.jalisco.gob.mx\/programa-sigamos-aprendiendo-hospital\/","title":{"rendered":"Inicio"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"11\" class=\"elementor elementor-11\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-25bf198 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"25bf198\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4db24b8\" data-id=\"4db24b8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-13099e7 elementor--v-position-top elementor--h-position-left elementor-hidden-tablet elementor-hidden-mobile elementor-widget-mobile_extra__width-initial elementor-arrows-position-inside elementor-pagination-position-inside elementor-widget elementor-widget-slides\" data-id=\"13099e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500,&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slides\" dir=\"ltr\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-750f281 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"bannerhospital\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7baf81c elementor--v-position-top elementor--h-position-left elementor-hidden-desktop elementor-hidden-laptop elementor-hidden-mobile_extra elementor-arrows-position-inside elementor-pagination-position-inside elementor-widget elementor-widget-slides\" data-id=\"7baf81c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500,&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slides\" dir=\"ltr\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-750f281 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\" role=\"img\" aria-label=\"movilhospital\"><\/div><div class=\"swiper-slide-inner\" ><div class=\"swiper-slide-contents\"><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7c41229 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"7c41229\" data-element_type=\"section\" data-e-type=\"section\" id=\"consulta\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1d9e0e1\" data-id=\"1d9e0e1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6efc8a5 elementor-widget elementor-widget-heading\" data-id=\"6efc8a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Consulta<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cd42216 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"cd42216\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-9deb7e9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9deb7e9\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5543305\" data-id=\"5543305\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4070610\" data-id=\"4070610\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-20ba74a elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle elementor-invisible\" data-id=\"20ba74a\" data-element_type=\"section\" data-e-type=\"section\" id=\"about\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-722e868\" data-id=\"722e868\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0a9c2bd elementor-widget elementor-widget-heading\" data-id=\"0a9c2bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">\u00bfQui\u00e9nes somos?<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2017441 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"2017441\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d22f59a elementor-widget elementor-widget-text-editor\" data-id=\"d22f59a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Sigamos Aprendiendo en el Hospital es un programa que, en coordinaci\u00f3n con el Sector Salud y la Secretar\u00eda de Educaci\u00f3n, brindan a las ni\u00f1as, ni\u00f1os y j\u00f3venes apoyo educativo, para atender las necesidades que por sus condiciones de salud pueden caer en rezago educativo, este apoyo se realiza en unidades hospitalarias.<b>\u00a0<\/b><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b1f9d53 elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"b1f9d53\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1861\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1861\" aria-expanded=\"false\">Misi\u00f3n<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1862\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1862\" aria-expanded=\"false\">Visi\u00f3n<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1863\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1863\" aria-expanded=\"false\">Objetivos<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1864\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"4\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1864\" aria-expanded=\"false\">Marco Normativo<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1865\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"5\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1865\" aria-expanded=\"false\">Servicios<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1861\" aria-expanded=\"false\">Misi\u00f3n<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1861\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1861\" tabindex=\"0\" hidden=\"false\"><p>Prevenir y atender el rezago educativo de ni\u00f1as, ni\u00f1os y j\u00f3venes en el contexto hospitalario, mediante un servicio profesional docente y con profundo sentido humano, satisfaciendo sus necesidades educativas que les facilite la continuidad de su Educaci\u00f3n B\u00e1sica y Media Superior.<\/p><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1862\" aria-expanded=\"false\">Visi\u00f3n<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1862\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1862\" tabindex=\"0\" hidden=\"hidden\">Que ni\u00f1as, ni\u00f1os y j\u00f3venes tengan la oportunidad de recibir el servicio educativo durante su hospitalizaci\u00f3n, que les permita de acuerdo a sus circunstancias mejorar su calidad de vida manteniendo la continuidad de su desarrollo integral con la mayor normalidad posible<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1863\" aria-expanded=\"false\">Objetivos<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1863\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1863\" tabindex=\"0\" hidden=\"hidden\"><p>Contribuir a la disminuci\u00f3n del rezago educativo de ni\u00f1as, ni\u00f1os y j\u00f3venes, que por motivos de salud han dejado de asistir a la escuela y se encuentran hospitalizados, en tratamientos, rehabilitaci\u00f3n o bien en casa convaleciendo, a trav\u00e9s de la atenci\u00f3n educativa, que responde a sus necesidades en el marco del contexto hospitalario.<\/p><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"4\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1864\" aria-expanded=\"false\">Marco Normativo<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1864\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1864\" tabindex=\"0\" hidden=\"hidden\"><p>Reglamento Interno de la Secretar\u00eda de Educaci\u00f3n del Estado de Jalisco<\/p><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"5\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1865\" aria-expanded=\"false\">Servicios<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1865\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1865\" tabindex=\"0\" hidden=\"hidden\">Atenci\u00f3n de servicio educativo (clases) de 8:00 hrs. a 16:00 horas de lunes a viernes seg\u00fan el calendario escolar vigente y el receso escolar.<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3738542 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"3738542\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-de176e3\" data-id=\"de176e3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2cde4b8 elementor-widget elementor-widget-heading\" data-id=\"2cde4b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Tr\u00e1mites y servicios<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5134b14 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5134b14\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-bfd9493\" data-id=\"bfd9493\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-2eb82e5\" data-id=\"2eb82e5\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a4f0ff2 elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"a4f0ff2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/apprende.jalisco.gob.mx\/programa-sigamos-aprendiendo-hospital\/tramite\/\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"Tr\u00e1mites\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-Profile\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/apprende.jalisco.gob.mx\/programa-sigamos-aprendiendo-hospital\/tramite\/\" >\n\t\t\t\t\t\t\tTr\u00e1mites\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tInscripci\u00f3n al programa\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-157e62f\" data-id=\"157e62f\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d3ff485 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"d3ff485\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d109d5d\" data-id=\"d109d5d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-de4749b elementor-widget elementor-widget-heading\" data-id=\"de4749b\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"contacto\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Informaci\u00f3n de Contacto<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e49c33d elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"e49c33d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8097f23 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8097f23\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-274b8bd\" data-id=\"274b8bd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8310f04 elementor-laptop-position-block-start elementor-tablet-position-block-start elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"8310f04\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-map-marker1\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h5 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tDirecci\u00f3n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tAv. Manuel \u00c1vila Camacho No. 1015, 4\u00ba piso, Colonia Miraflores, C.P. 44270, Guadalajara, Jalisco.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b656bb elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"7b656bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-e4f0663\" data-id=\"e4f0663\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b987104 elementor-laptop-position-block-start elementor-tablet-position-block-start elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"b987104\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-phone1\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h5 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tCont\u00e1ctanos\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t33 3030-35951 y 33 3030-5952 Exts. 56031 y 56002\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dc83110 elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"dc83110\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-3b03b4b\" data-id=\"3b03b4b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ef97721 elementor-laptop-position-block-start elementor-tablet-position-block-start elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"ef97721\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-clock2\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h5 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tHorario de atenci\u00f3n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t09:00 AM - 05:00 PM\nLunes - Viernes\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-baed96d elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"baed96d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-256dee3\" data-id=\"256dee3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-315502d elementor-laptop-position-block-start elementor-tablet-position-block-start elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"315502d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-user-1\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h5 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tTitular\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tAlejandro Lisjuan Bracamontes, Encargado del Programa\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1606840 elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"1606840\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Consulta \u00bfQui\u00e9nes somos? Sigamos Aprendiendo en el Hospital es un programa que, en coordinaci\u00f3n con el Sector Salud y la Secretar\u00eda de Educaci\u00f3n, brindan a las ni\u00f1as, ni\u00f1os y j\u00f3venes apoyo educativo, para atender las necesidades que por sus condiciones de salud pueden caer en rezago educativo, este apoyo se realiza en unidades hospitalarias.\u00a0 Misi\u00f3n &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/apprende.jalisco.gob.mx\/programa-sigamos-aprendiendo-hospital\/\"> <span class=\"screen-reader-text\">Inicio<\/span> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"disabled","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"","ep_exclude_from_search":false,"footnotes":""},"class_list":["post-11","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Inicio - Programa Sigamos Aprendiendo en el Hospital<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/apprende.jalisco.gob.mx\/programa-sigamos-aprendiendo-hospital\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Inicio - Programa Sigamos Aprendiendo en el Hospital\" \/>\n<meta property=\"og:description\" content=\"Consulta \u00bfQui\u00e9nes somos? Sigamos Aprendiendo en el Hospital es un programa que, en coordinaci\u00f3n con el Sector Salud y la Secretar\u00eda de Educaci\u00f3n, brindan a las ni\u00f1as, ni\u00f1os y j\u00f3venes apoyo educativo, para atender las necesidades que por sus condiciones de salud pueden caer en rezago educativo, este apoyo se realiza en unidades hospitalarias.\u00a0 Misi\u00f3n &hellip; Inicio Leer m\u00e1s &raquo;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/apprende.jalisco.gob.mx\/programa-sigamos-aprendiendo-hospital\/\" \/>\n<meta property=\"og:site_name\" content=\"Programa Sigamos Aprendiendo en el Hospital\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-28T16:56:55+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/apprende.jalisco.gob.mx\\\/programa-sigamos-aprendiendo-hospital\\\/\",\"url\":\"https:\\\/\\\/apprende.jalisco.gob.mx\\\/programa-sigamos-aprendiendo-hospital\\\/\",\"name\":\"Inicio - Programa Sigamos Aprendiendo en el Hospital\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/apprende.jalisco.gob.mx\\\/programa-sigamos-aprendiendo-hospital\\\/#website\"},\"datePublished\":\"2022-03-17T18:40:56+00:00\",\"dateModified\":\"2026-01-28T16:56:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/apprende.jalisco.gob.mx\\\/programa-sigamos-aprendiendo-hospital\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/apprende.jalisco.gob.mx\\\/programa-sigamos-aprendiendo-hospital\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/apprende.jalisco.gob.mx\\\/programa-sigamos-aprendiendo-hospital\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/apprende.jalisco.gob.mx\\\/programa-sigamos-aprendiendo-hospital\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Inicio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/apprende.jalisco.gob.mx\\\/programa-sigamos-aprendiendo-hospital\\\/#website\",\"url\":\"https:\\\/\\\/apprende.jalisco.gob.mx\\\/programa-sigamos-aprendiendo-hospital\\\/\",\"name\":\"Programa Sigamos Aprendiendo en el Hospital\",\"description\":\"Micrositio\",\"publisher\":{\"@id\":\"https:\\\/\\\/apprende.jalisco.gob.mx\\\/programa-sigamos-aprendiendo-hospital\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/apprende.jalisco.gob.mx\\\/programa-sigamos-aprendiendo-hospital\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/apprende.jalisco.gob.mx\\\/programa-sigamos-aprendiendo-hospital\\\/#organization\",\"name\":\"Programa Sigamos Aprendiendo en el Hospital\",\"url\":\"https:\\\/\\\/apprende.jalisco.gob.mx\\\/programa-sigamos-aprendiendo-hospital\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/apprende.jalisco.gob.mx\\\/programa-sigamos-aprendiendo-hospital\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/apprende.jalisco.gob.mx\\\/programa-sigamos-aprendiendo-hospital\\\/wp-content\\\/uploads\\\/sites\\\/27\\\/2022\\\/03\\\/logo-Educacion2025.png\",\"contentUrl\":\"https:\\\/\\\/apprende.jalisco.gob.mx\\\/programa-sigamos-aprendiendo-hospital\\\/wp-content\\\/uploads\\\/sites\\\/27\\\/2022\\\/03\\\/logo-Educacion2025.png\",\"width\":427,\"height\":108,\"caption\":\"Programa Sigamos Aprendiendo en el Hospital\"},\"image\":{\"@id\":\"https:\\\/\\\/apprende.jalisco.gob.mx\\\/programa-sigamos-aprendiendo-hospital\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Inicio - Programa Sigamos Aprendiendo en el Hospital","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/apprende.jalisco.gob.mx\/programa-sigamos-aprendiendo-hospital\/","og_locale":"es_MX","og_type":"article","og_title":"Inicio - Programa Sigamos Aprendiendo en el Hospital","og_description":"Consulta \u00bfQui\u00e9nes somos? Sigamos Aprendiendo en el Hospital es un programa que, en coordinaci\u00f3n con el Sector Salud y la Secretar\u00eda de Educaci\u00f3n, brindan a las ni\u00f1as, ni\u00f1os y j\u00f3venes apoyo educativo, para atender las necesidades que por sus condiciones de salud pueden caer en rezago educativo, este apoyo se realiza en unidades hospitalarias.\u00a0 Misi\u00f3n &hellip; Inicio Leer m\u00e1s &raquo;","og_url":"https:\/\/apprende.jalisco.gob.mx\/programa-sigamos-aprendiendo-hospital\/","og_site_name":"Programa Sigamos Aprendiendo en el Hospital","article_modified_time":"2026-01-28T16:56:55+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/apprende.jalisco.gob.mx\/programa-sigamos-aprendiendo-hospital\/","url":"https:\/\/apprende.jalisco.gob.mx\/programa-sigamos-aprendiendo-hospital\/","name":"Inicio - Programa Sigamos Aprendiendo en el Hospital","isPartOf":{"@id":"https:\/\/apprende.jalisco.gob.mx\/programa-sigamos-aprendiendo-hospital\/#website"},"datePublished":"2022-03-17T18:40:56+00:00","dateModified":"2026-01-28T16:56:55+00:00","breadcrumb":{"@id":"https:\/\/apprende.jalisco.gob.mx\/programa-sigamos-aprendiendo-hospital\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/apprende.jalisco.gob.mx\/programa-sigamos-aprendiendo-hospital\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/apprende.jalisco.gob.mx\/programa-sigamos-aprendiendo-hospital\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/apprende.jalisco.gob.mx\/programa-sigamos-aprendiendo-hospital\/"},{"@type":"ListItem","position":2,"name":"Inicio"}]},{"@type":"WebSite","@id":"https:\/\/apprende.jalisco.gob.mx\/programa-sigamos-aprendiendo-hospital\/#website","url":"https:\/\/apprende.jalisco.gob.mx\/programa-sigamos-aprendiendo-hospital\/","name":"Programa Sigamos Aprendiendo en el Hospital","description":"Micrositio","publisher":{"@id":"https:\/\/apprende.jalisco.gob.mx\/programa-sigamos-aprendiendo-hospital\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/apprende.jalisco.gob.mx\/programa-sigamos-aprendiendo-hospital\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/apprende.jalisco.gob.mx\/programa-sigamos-aprendiendo-hospital\/#organization","name":"Programa Sigamos Aprendiendo en el Hospital","url":"https:\/\/apprende.jalisco.gob.mx\/programa-sigamos-aprendiendo-hospital\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/apprende.jalisco.gob.mx\/programa-sigamos-aprendiendo-hospital\/#\/schema\/logo\/image\/","url":"https:\/\/apprende.jalisco.gob.mx\/programa-sigamos-aprendiendo-hospital\/wp-content\/uploads\/sites\/27\/2022\/03\/logo-Educacion2025.png","contentUrl":"https:\/\/apprende.jalisco.gob.mx\/programa-sigamos-aprendiendo-hospital\/wp-content\/uploads\/sites\/27\/2022\/03\/logo-Educacion2025.png","width":427,"height":108,"caption":"Programa Sigamos Aprendiendo en el Hospital"},"image":{"@id":"https:\/\/apprende.jalisco.gob.mx\/programa-sigamos-aprendiendo-hospital\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/apprende.jalisco.gob.mx\/programa-sigamos-aprendiendo-hospital\/wp-json\/wp\/v2\/pages\/11","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/apprende.jalisco.gob.mx\/programa-sigamos-aprendiendo-hospital\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/apprende.jalisco.gob.mx\/programa-sigamos-aprendiendo-hospital\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/apprende.jalisco.gob.mx\/programa-sigamos-aprendiendo-hospital\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/apprende.jalisco.gob.mx\/programa-sigamos-aprendiendo-hospital\/wp-json\/wp\/v2\/comments?post=11"}],"version-history":[{"count":1167,"href":"https:\/\/apprende.jalisco.gob.mx\/programa-sigamos-aprendiendo-hospital\/wp-json\/wp\/v2\/pages\/11\/revisions"}],"predecessor-version":[{"id":3687,"href":"https:\/\/apprende.jalisco.gob.mx\/programa-sigamos-aprendiendo-hospital\/wp-json\/wp\/v2\/pages\/11\/revisions\/3687"}],"wp:attachment":[{"href":"https:\/\/apprende.jalisco.gob.mx\/programa-sigamos-aprendiendo-hospital\/wp-json\/wp\/v2\/media?parent=11"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}